{"id":1539,"date":"2023-01-06T11:32:37","date_gmt":"2023-01-06T11:32:37","guid":{"rendered":"https:\/\/www.laescueladelagua.com\/?p=1539"},"modified":"2023-07-13T11:41:40","modified_gmt":"2023-07-13T11:41:40","slug":"ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua","status":"publish","type":"post","link":"https:\/\/www.laescueladelagua.com\/ca\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/","title":{"rendered":"Ajuda YEAR OF SKILLS 2023: aposta per la teva formaci\u00f3 amb l&#039;Escola de l&#039;Aigua"},"content":{"rendered":"<p><em>L&#039;Escola de l&#039;Aigua d&#039;Agbar vol oferir la millor formaci\u00f3 als professionals presents i futurs del sector de l&#039;aigua, i per aix\u00f2 llan\u00e7a noves ajudes en forma de descomptes directes per als seus programes d&#039;educaci\u00f3 superior.<\/em><\/p>\n<p>L&#039;any 2023 ha estat declarat com a l&#039;Any Europeu de les Capacitats per les institucions europees. La proposta de la Comissi\u00f3 Europea se sustenta en el fet que la transici\u00f3 digital i les compet\u00e8ncies verdes estan obrint noves oportunitats per a les persones i l&#039;economia de la UE. Tenir les habilitats necess\u00e0ries empodera les persones per reorientar-se i enfocar-se amb \u00e8xit als canvis del mercat laboral ia la societat, assegurant que ning\u00fa no es quedi enrere i que la transici\u00f3 verda i digital sigui socialment justa.<\/p>\n<p>En aquest context, i amb l&#039;objectiu de sumar-se a l&#039;impuls de les skills el 2023, l&#039;Escola de l&#039;Aigua est\u00e9n a <strong>tota la ciutadania de la Uni\u00f3 Europea un ajut directe d&#039;un 10%<\/strong>, a la matr\u00edcula del <a href=\"\/ca\/programa\/masters-y-posgrados\/master\/master-online-en-tecnologia-y-gestion-del-agua\/\" target=\"_blank\" rel=\"noopener\">M\u00e0ster Online en Tecnologia i Gesti\u00f3 de l&#039;Aigua<\/a> i Postgraus T\u00e8cnics a Abastament oa Xarxes d&#039;Aigua que inicien al Mar\u00e7. Aquest ajut \u00e9s acumulable amb la resta d&#039;incentius disponibles, t\u00e9 places limitades i nom\u00e9s estar\u00e0 disponible <strong>fins al 31 de gener de 2023<\/strong>. L&#039;ajut s&#039;aplicar\u00e0 per estricte ordre de registre i fins a completar les places disponibles<\/p>\n<p>Una altra de les novetats que cal destacar d&#039;aquest inici d&#039;any \u00e9s l&#039;obertura, fins al 24 de febrer, del termini per presentar la candidatura al <strong>Programa Excel\u00b7l\u00e8ncia<\/strong>, que compta amb <strong>2 beques per cobrir el 50% del valor del M\u00e0ster<\/strong>; aquests ajuts estan destinats a facilitar l&#039;acc\u00e9s a la formaci\u00f3 superior dels joves <strong>menors de 35 anys amb bons expedients acad\u00e8mics i\/o professionals<\/strong>. Consulta les bases <a href=\"\/wp-content\/uploads\/2023\/07\/Bases-Programa-Excelencia_Master-Online_Mz23.pdf\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n<p><strong>M\u00c0STER EN TECNOLOGIA I GESTI\u00d3 DE L&#039;AIGUA: COMPET\u00c8NCIES VERDES, T\u00c8CNIQUES I DIRECTIVES PER LIDERAR EL FUTUR DE L&#039;AIGUA<\/strong><\/p>\n<p>Pensat per a perfils t\u00e8cnics i gerencials, t\u00e9 com a objectiu principal dotar els participants d&#039;una visi\u00f3 integral de la gesti\u00f3 del cicle urb\u00e0 de l&#039;aigua i de les compet\u00e8ncies directives per a la presa de decisions estrat\u00e8giques alineades amb els Objectius de Desenvolupament Sostenible (ODS) en empreses i organismes operadors d&#039;aigua<\/p>\n<p>Contacta i resol tots els dubtes amb el nostre equip d&#039;assessors acad\u00e8mics a <a href=\"mailto:admisiones@laescueladelagua.com\">admissions@laescoladelagua.com<\/a>, tel\u00e8fon +34 93 247 97 35 o WhatsApp +34 616778523<\/p>\n<p>No deixis passar aquesta oportunitat!<\/p>","protected":false},"excerpt":{"rendered":"<p>L&#039;Escola de l&#039;Aigua d&#039;Agbar vol oferir la millor formaci\u00f3 als professionals presents i futurs del sector de l&#039;aigua, i per aix\u00f2 llan\u00e7a noves ajudes en forma de descomptes directes per als seus programes d&#039;educaci\u00f3 superior. L&#039;any 2023 ha estat declarat com l&#039;Any Europeu de les Capacitats [\u2026]<\/p>","protected":false},"author":1,"featured_media":1541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-1539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Ayuda YEAR OF SKILLS 2023: apuesta por tu formaci\u00f3n con la Escuela del Agua - Escuela del agua<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.laescueladelagua.com\/ca\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/\" \/>\r\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Ayuda YEAR OF SKILLS 2023: apuesta por tu formaci\u00f3n con la Escuela del Agua - Escuela del agua\" \/>\r\n<meta property=\"og:description\" content=\"La Escuela del Agua de Agbar quiere ofrecer la mejor formaci\u00f3n a los y las profesionales presentes y futuros del sector del agua, y para ello lanza nuevas ayudas en forma de descuentos directos para sus programas de educaci\u00f3n superior. El a\u00f1o 2023 ha sido declarado como el A\u00f1o Europeo de las Capacidades por las [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.laescueladelagua.com\/ca\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Escuela del agua\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-01-06T11:32:37+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-07-13T11:41:40+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.laescueladelagua.com\/wp-content\/uploads\/2023\/07\/article-36-e1698070321254.jpeg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"215\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"adminusr\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminusr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/\"},\"author\":{\"name\":\"adminusr\",\"@id\":\"https:\/\/wapwebedapro01.azurewebsites.net\/#\/schema\/person\/dd1649223e405b6f9eb82e8f6798f241\"},\"headline\":\"Ayuda YEAR OF SKILLS 2023: apuesta por tu formaci\u00f3n con la Escuela del Agua\",\"datePublished\":\"2023-01-06T11:32:37+00:00\",\"dateModified\":\"2023-07-13T11:41:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/\"},\"wordCount\":434,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/wapwebedapro01.azurewebsites.net\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#primaryimage\"},\"thumbnailUrl\":\"\/wp-content\/uploads\/2023\/07\/article-36-e1698070321254.jpeg\",\"articleSection\":[\"Programas\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/\",\"url\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/\",\"name\":\"Ayuda YEAR OF SKILLS 2023: apuesta por tu formaci\u00f3n con la Escuela del Agua - Escuela del agua\",\"isPartOf\":{\"@id\":\"https:\/\/wapwebedapro01.azurewebsites.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#primaryimage\"},\"thumbnailUrl\":\"\/wp-content\/uploads\/2023\/07\/article-36-e1698070321254.jpeg\",\"datePublished\":\"2023-01-06T11:32:37+00:00\",\"dateModified\":\"2023-07-13T11:41:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#primaryimage\",\"url\":\"\/wp-content\/uploads\/2023\/07\/article-36-e1698070321254.jpeg\",\"contentUrl\":\"\/wp-content\/uploads\/2023\/07\/article-36-e1698070321254.jpeg\",\"width\":800,\"height\":215},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wapwebedapro01.azurewebsites.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayuda YEAR OF SKILLS 2023: apuesta por tu formaci\u00f3n con la Escuela del Agua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wapwebedapro01.azurewebsites.net\/#website\",\"url\":\"https:\/\/wapwebedapro01.azurewebsites.net\/\",\"name\":\"Escuela del agua\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/wapwebedapro01.azurewebsites.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wapwebedapro01.azurewebsites.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wapwebedapro01.azurewebsites.net\/#organization\",\"name\":\"Escuela del agua\",\"url\":\"https:\/\/wapwebedapro01.azurewebsites.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/wapwebedapro01.azurewebsites.net\/#\/schema\/logo\/image\/\",\"url\":\"\/wp-content\/uploads\/2023\/08\/logo_EscueladelAgua_mod.1.1_150px.png\",\"contentUrl\":\"\/wp-content\/uploads\/2023\/08\/logo_EscueladelAgua_mod.1.1_150px.png\",\"width\":150,\"height\":90,\"caption\":\"Escuela del agua\"},\"image\":{\"@id\":\"https:\/\/wapwebedapro01.azurewebsites.net\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/wapwebedapro01.azurewebsites.net\/#\/schema\/person\/dd1649223e405b6f9eb82e8f6798f241\",\"name\":\"adminusr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/wapwebedapro01.azurewebsites.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0faaa87907e163fd330069f117adf408?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0faaa87907e163fd330069f117adf408?s=96&d=mm&r=g\",\"caption\":\"adminusr\"},\"sameAs\":[\"https:\/\/www.laescueladelagua.com\"],\"url\":\"https:\/\/www.laescueladelagua.com\/ca\/author\/adminusr\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ayuda YEAR OF SKILLS 2023: apuesta por tu formaci\u00f3n con la Escuela del Agua - Escuela del agua","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laescueladelagua.com\/ca\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/","og_locale":"ca_ES","og_type":"article","og_title":"Ayuda YEAR OF SKILLS 2023: apuesta por tu formaci\u00f3n con la Escuela del Agua - Escuela del agua","og_description":"La Escuela del Agua de Agbar quiere ofrecer la mejor formaci\u00f3n a los y las profesionales presentes y futuros del sector del agua, y para ello lanza nuevas ayudas en forma de descuentos directos para sus programas de educaci\u00f3n superior. El a\u00f1o 2023 ha sido declarado como el A\u00f1o Europeo de las Capacidades por las [&hellip;]","og_url":"https:\/\/www.laescueladelagua.com\/ca\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/","og_site_name":"Escuela del agua","article_published_time":"2023-01-06T11:32:37+00:00","article_modified_time":"2023-07-13T11:41:40+00:00","og_image":[{"width":800,"height":215,"url":"https:\/\/www.laescueladelagua.com\/wp-content\/uploads\/2023\/07\/article-36-e1698070321254.jpeg","type":"image\/jpeg"}],"author":"adminusr","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"adminusr","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#article","isPartOf":{"@id":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/"},"author":{"name":"adminusr","@id":"https:\/\/wapwebedapro01.azurewebsites.net\/#\/schema\/person\/dd1649223e405b6f9eb82e8f6798f241"},"headline":"Ayuda YEAR OF SKILLS 2023: apuesta por tu formaci\u00f3n con la Escuela del Agua","datePublished":"2023-01-06T11:32:37+00:00","dateModified":"2023-07-13T11:41:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/"},"wordCount":434,"commentCount":0,"publisher":{"@id":"https:\/\/wapwebedapro01.azurewebsites.net\/#organization"},"image":{"@id":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2023\/07\/article-36-e1698070321254.jpeg","articleSection":["Programas"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/","url":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/","name":"Ayuda YEAR OF SKILLS 2023: apuesta por tu formaci\u00f3n con la Escuela del Agua - Escuela del agua","isPartOf":{"@id":"https:\/\/wapwebedapro01.azurewebsites.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#primaryimage"},"image":{"@id":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2023\/07\/article-36-e1698070321254.jpeg","datePublished":"2023-01-06T11:32:37+00:00","dateModified":"2023-07-13T11:41:40+00:00","breadcrumb":{"@id":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#primaryimage","url":"\/wp-content\/uploads\/2023\/07\/article-36-e1698070321254.jpeg","contentUrl":"\/wp-content\/uploads\/2023\/07\/article-36-e1698070321254.jpeg","width":800,"height":215},{"@type":"BreadcrumbList","@id":"https:\/\/www.laescueladelagua.com\/en\/ayuda-year-of-skills-2023-apuesta-por-tu-formacion-con-la-escuela-del-agua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wapwebedapro01.azurewebsites.net\/"},{"@type":"ListItem","position":2,"name":"Ayuda YEAR OF SKILLS 2023: apuesta por tu formaci\u00f3n con la Escuela del Agua"}]},{"@type":"WebSite","@id":"https:\/\/wapwebedapro01.azurewebsites.net\/#website","url":"https:\/\/wapwebedapro01.azurewebsites.net\/","name":"Escuela del agua","description":"","publisher":{"@id":"https:\/\/wapwebedapro01.azurewebsites.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wapwebedapro01.azurewebsites.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/wapwebedapro01.azurewebsites.net\/#organization","name":"Escuela del agua","url":"https:\/\/wapwebedapro01.azurewebsites.net\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/wapwebedapro01.azurewebsites.net\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2023\/08\/logo_EscueladelAgua_mod.1.1_150px.png","contentUrl":"\/wp-content\/uploads\/2023\/08\/logo_EscueladelAgua_mod.1.1_150px.png","width":150,"height":90,"caption":"Escuela del agua"},"image":{"@id":"https:\/\/wapwebedapro01.azurewebsites.net\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wapwebedapro01.azurewebsites.net\/#\/schema\/person\/dd1649223e405b6f9eb82e8f6798f241","name":"adminusr","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/wapwebedapro01.azurewebsites.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0faaa87907e163fd330069f117adf408?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0faaa87907e163fd330069f117adf408?s=96&d=mm&r=g","caption":"adminusr"},"sameAs":["https:\/\/www.laescueladelagua.com"],"url":"https:\/\/www.laescueladelagua.com\/ca\/author\/adminusr\/"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/posts\/1539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/comments?post=1539"}],"version-history":[{"count":2,"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/posts\/1539\/revisions"}],"predecessor-version":[{"id":1543,"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/posts\/1539\/revisions\/1543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/media\/1541"}],"wp:attachment":[{"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/media?parent=1539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/categories?post=1539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laescueladelagua.com\/ca\/wp-json\/wp\/v2\/tags?post=1539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}